{"id":35,"count":3,"description":"","link":"https:\/\/personal-polen.de\/en\/category\/lohn\/","name":"Wage","slug":"wage","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lohn Archive - Personal aus Polen<\/title>\n<meta name=\"description\" content=\"Willkommen bei Personal aus Polen. Wir sind Ihr spezialisierter Dienstleister f\u00fcr Subunternehmer, Handwerker und Leiharbeiter aus Polen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/personal-polen.de\/en\/category\/wage\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lohn Archive\" \/>\n<meta property=\"og:description\" content=\"Willkommen bei Personal aus Polen. Wir sind Ihr spezialisierter Dienstleister f\u00fcr Subunternehmer, Handwerker und Leiharbeiter aus Polen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/personal-polen.de\/en\/category\/wage\/\" \/>\n<meta property=\"og:site_name\" content=\"Personal aus Polen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/personal-polen.de\\\/category\\\/lohn\\\/\",\"url\":\"https:\\\/\\\/personal-polen.de\\\/category\\\/lohn\\\/\",\"name\":\"Lohn Archive - Personal aus Polen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/personal-polen.de\\\/#website\"},\"description\":\"Willkommen bei Personal aus Polen. Wir sind Ihr spezialisierter Dienstleister f\u00fcr Subunternehmer, Handwerker und Leiharbeiter aus Polen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/personal-polen.de\\\/category\\\/lohn\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/personal-polen.de\\\/category\\\/lohn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/personal-polen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lohn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/personal-polen.de\\\/#website\",\"url\":\"https:\\\/\\\/personal-polen.de\\\/\",\"name\":\"Personal aus Polen\",\"description\":\"Ihr Spezialist f\u00fcr Handwerker und Subunternehmer aus Polen\",\"publisher\":{\"@id\":\"https:\\\/\\\/personal-polen.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/personal-polen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/personal-polen.de\\\/#organization\",\"name\":\"Personal aus Polen\",\"url\":\"https:\\\/\\\/personal-polen.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/personal-polen.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/personal-polen.de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/pal_logo_2.png\",\"contentUrl\":\"https:\\\/\\\/personal-polen.de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/pal_logo_2.png\",\"width\":250,\"height\":100,\"caption\":\"Personal aus Polen\"},\"image\":{\"@id\":\"https:\\\/\\\/personal-polen.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lohn Archive - Personal aus Polen","description":"Welcome to Personnel from Poland. We are your specialised service provider for subcontractors, craftsmen and temporary workers from Poland.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/personal-polen.de\/en\/category\/wage\/","og_locale":"en_GB","og_type":"article","og_title":"Lohn Archive","og_description":"Willkommen bei Personal aus Polen. Wir sind Ihr spezialisierter Dienstleister f\u00fcr Subunternehmer, Handwerker und Leiharbeiter aus Polen.","og_url":"https:\/\/personal-polen.de\/en\/category\/wage\/","og_site_name":"Personal aus Polen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/personal-polen.de\/category\/lohn\/","url":"https:\/\/personal-polen.de\/category\/lohn\/","name":"Wages Archive - Personnel from Poland","isPartOf":{"@id":"https:\/\/personal-polen.de\/#website"},"description":"Welcome to Personnel from Poland. We are your specialised service provider for subcontractors, craftsmen and temporary workers from Poland.","breadcrumb":{"@id":"https:\/\/personal-polen.de\/category\/lohn\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/personal-polen.de\/category\/lohn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/personal-polen.de\/"},{"@type":"ListItem","position":2,"name":"Lohn"}]},{"@type":"WebSite","@id":"https:\/\/personal-polen.de\/#website","url":"https:\/\/personal-polen.de\/","name":"Staff from Poland","description":"Your specialist for craftsmen and subcontractors from Poland","publisher":{"@id":"https:\/\/personal-polen.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/personal-polen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/personal-polen.de\/#organization","name":"Staff from Poland","url":"https:\/\/personal-polen.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/personal-polen.de\/#\/schema\/logo\/image\/","url":"https:\/\/personal-polen.de\/wp-content\/uploads\/2019\/02\/pal_logo_2.png","contentUrl":"https:\/\/personal-polen.de\/wp-content\/uploads\/2019\/02\/pal_logo_2.png","width":250,"height":100,"caption":"Personal aus Polen"},"image":{"@id":"https:\/\/personal-polen.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/personal-polen.de\/en\/wp-json\/wp\/v2\/categories\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/personal-polen.de\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/personal-polen.de\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/personal-polen.de\/en\/wp-json\/wp\/v2\/posts?categories=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}